{"id":2116,"date":"2023-01-20T14:51:54","date_gmt":"2023-01-20T14:51:54","guid":{"rendered":"https:\/\/glassense.com\/toode\/staapli-noblessner\/"},"modified":"2023-01-20T14:51:54","modified_gmt":"2023-01-20T14:51:54","slug":"staapli-noblessner","status":"publish","type":"tooted","link":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/","title":{"rendered":"Noblessner &#8211; Staapli"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Triple Insulating glasses with Cool-Lite SKN 176 Solar protection and laminated safety glass<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Triple Insulating glasses with Cool-Lite SKN 176 Solar protection and laminated safety glass<\/p>\n","protected":false},"featured_media":1918,"parent":0,"template":"","categories":[45],"class_list":["post-2116","tooted","type-tooted","status-publish","has-post-thumbnail","hentry","category-aknad-et"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noblessner - Staapli - admin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noblessner - Staapli - admin\" \/>\n<meta property=\"og:description\" content=\"Triple Insulating glasses with Cool-Lite SKN 176 Solar protection and laminated safety glass\" \/>\n<meta property=\"og:url\" content=\"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/\" \/>\n<meta property=\"og:site_name\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/staapli-noblessner\\\/\",\"url\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/staapli-noblessner\\\/\",\"name\":\"Noblessner - Staapli - admin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/staapli-noblessner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/staapli-noblessner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/glassense.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Staapli-01-scaled.jpg\",\"datePublished\":\"2023-01-20T14:51:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/staapli-noblessner\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/staapli-noblessner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/staapli-noblessner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/glassense.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Staapli-01-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/glassense.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Staapli-01-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/staapli-noblessner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/glassense.com\\\/et\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Noblessner &#8211; Staapli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/#website\",\"url\":\"https:\\\/\\\/glassense.com\\\/et\\\/\",\"name\":\"admin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/glassense.com\\\/et\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noblessner - Staapli - admin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/","og_locale":"et_EE","og_type":"article","og_title":"Noblessner - Staapli - admin","og_description":"Triple Insulating glasses with Cool-Lite SKN 176 Solar protection and laminated safety glass","og_url":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/","og_site_name":"admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/","url":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/","name":"Noblessner - Staapli - admin","isPartOf":{"@id":"https:\/\/glassense.com\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/#primaryimage"},"image":{"@id":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/#primaryimage"},"thumbnailUrl":"https:\/\/glassense.com\/wp-content\/uploads\/2023\/01\/Staapli-01-scaled.jpg","datePublished":"2023-01-20T14:51:54+00:00","breadcrumb":{"@id":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/glassense.com\/et\/product\/staapli-noblessner\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/#primaryimage","url":"https:\/\/glassense.com\/wp-content\/uploads\/2023\/01\/Staapli-01-scaled.jpg","contentUrl":"https:\/\/glassense.com\/wp-content\/uploads\/2023\/01\/Staapli-01-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/glassense.com\/et\/product\/staapli-noblessner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/glassense.com\/et\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/glassense.com\/et\/product\/"},{"@type":"ListItem","position":3,"name":"Noblessner &#8211; Staapli"}]},{"@type":"WebSite","@id":"https:\/\/glassense.com\/et\/#website","url":"https:\/\/glassense.com\/et\/","name":"admin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/glassense.com\/et\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"}]}},"_links":{"self":[{"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/tooted\/2116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/tooted"}],"about":[{"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/types\/tooted"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/media\/1918"}],"wp:attachment":[{"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/media?parent=2116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/categories?post=2116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}