{"id":1186,"date":"2023-01-11T12:29:51","date_gmt":"2023-01-11T12:29:51","guid":{"rendered":"https:\/\/glassense.com\/toode\/postimees-group-hq\/"},"modified":"2023-01-11T17:41:58","modified_gmt":"2023-01-11T17:41:58","slug":"postimees-group-hq","status":"publish","type":"tooted","link":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/","title":{"rendered":"Postimees Group HQ"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Triple IGU-s with tempered and laminated glasses. Shapes and SG solutions. Solar protection glasses SunGuard SN 70\/35 and SN 40\/23<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Triple IGU-s with tempered and laminated glasses. Shapes and SG solutions. Solar protection glasses SunGuard&#8230;<\/p>\n","protected":false},"featured_media":584,"parent":0,"template":"","categories":[43],"class_list":["post-1186","tooted","type-tooted","status-publish","has-post-thumbnail","hentry","category-fassaadid-et"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Postimees Group HQ - admin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Postimees Group HQ - admin\" \/>\n<meta property=\"og:description\" content=\"Triple IGU-s with tempered and laminated glasses. Shapes and SG solutions. Solar protection glasses SunGuard...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/\" \/>\n<meta property=\"og:site_name\" content=\"admin\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-11T17:41:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/glassense.com\/wp-content\/uploads\/2023\/01\/Eesti-meedia_big-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/postimees-group-hq\\\/\",\"url\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/postimees-group-hq\\\/\",\"name\":\"Postimees Group HQ - admin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/postimees-group-hq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/postimees-group-hq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/glassense.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Eesti-meedia_big-scaled.jpg\",\"datePublished\":\"2023-01-11T12:29:51+00:00\",\"dateModified\":\"2023-01-11T17:41:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/postimees-group-hq\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/postimees-group-hq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/postimees-group-hq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/glassense.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Eesti-meedia_big-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/glassense.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Eesti-meedia_big-scaled.jpg\",\"width\":2560,\"height\":1439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/postimees-group-hq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/glassense.com\\\/et\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/glassense.com\\\/et\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Postimees Group HQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/glassense.com\\\/et\\\/#website\",\"url\":\"https:\\\/\\\/glassense.com\\\/et\\\/\",\"name\":\"admin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/glassense.com\\\/et\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Postimees Group HQ - admin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/","og_locale":"et_EE","og_type":"article","og_title":"Postimees Group HQ - admin","og_description":"Triple IGU-s with tempered and laminated glasses. Shapes and SG solutions. Solar protection glasses SunGuard...","og_url":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/","og_site_name":"admin","article_modified_time":"2023-01-11T17:41:58+00:00","og_image":[{"width":2560,"height":1439,"url":"https:\/\/glassense.com\/wp-content\/uploads\/2023\/01\/Eesti-meedia_big-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/","url":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/","name":"Postimees Group HQ - admin","isPartOf":{"@id":"https:\/\/glassense.com\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/#primaryimage"},"image":{"@id":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/#primaryimage"},"thumbnailUrl":"https:\/\/glassense.com\/wp-content\/uploads\/2023\/01\/Eesti-meedia_big-scaled.jpg","datePublished":"2023-01-11T12:29:51+00:00","dateModified":"2023-01-11T17:41:58+00:00","breadcrumb":{"@id":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/glassense.com\/et\/product\/postimees-group-hq\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/#primaryimage","url":"https:\/\/glassense.com\/wp-content\/uploads\/2023\/01\/Eesti-meedia_big-scaled.jpg","contentUrl":"https:\/\/glassense.com\/wp-content\/uploads\/2023\/01\/Eesti-meedia_big-scaled.jpg","width":2560,"height":1439},{"@type":"BreadcrumbList","@id":"https:\/\/glassense.com\/et\/product\/postimees-group-hq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/glassense.com\/et\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/glassense.com\/et\/product\/"},{"@type":"ListItem","position":3,"name":"Postimees Group HQ"}]},{"@type":"WebSite","@id":"https:\/\/glassense.com\/et\/#website","url":"https:\/\/glassense.com\/et\/","name":"admin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/glassense.com\/et\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"}]}},"_links":{"self":[{"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/tooted\/1186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/tooted"}],"about":[{"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/types\/tooted"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/media\/584"}],"wp:attachment":[{"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/media?parent=1186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/glassense.com\/et\/wp-json\/wp\/v2\/categories?post=1186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}